{"id":19060,"date":"2026-05-12T18:13:44","date_gmt":"2026-05-12T21:13:44","guid":{"rendered":"https:\/\/ibape-nacional.com.br\/site\/?p=19060"},"modified":"2026-05-12T18:16:06","modified_gmt":"2026-05-12T21:16:06","slug":"presidente-e-conselheiro-do-ibape-participam-de-reuniao-do-cesa-para-divulgacao-de-publicacao-sobre-pericias-da-abnt","status":"publish","type":"post","link":"https:\/\/ibape-nacional.com.br\/site\/presidente-e-conselheiro-do-ibape-participam-de-reuniao-do-cesa-para-divulgacao-de-publicacao-sobre-pericias-da-abnt\/","title":{"rendered":"Presidente e conselheiro do IBAPE participam de reuni\u00e3o do CESA para divulga\u00e7\u00e3o de publica\u00e7\u00e3o sobre per\u00edcias da ABNT"},"content":{"rendered":"<p><!--more--><\/p>\n<p>A presidente do IBAPE Nacional, <strong>Eng. Andrea Kl\u00fcppel Munhoz Soares<\/strong>, e o conselheiro <strong>Eng. Francisco Maia Neto<\/strong> participaram da reuni\u00e3o do <strong>Comit\u00ea de Direito Imobili\u00e1rio, Constru\u00e7\u00e3o e Infraestrutura do CESA (Centro de Estudos das Sociedades de Advogados)<\/strong>, realizada no dia 11 de maio, em formato h\u00edbrido.<\/p>\n<div>\n<p>O encontro teve como tema central <strong>\u201cA norma de per\u00edcias da ABNT para operadores do direito\u201d<\/strong>, reunindo profissionais e especialistas para discutir a import\u00e2ncia da aplica\u00e7\u00e3o das normas t\u00e9cnicas no contexto jur\u00eddico, especialmente em processos que envolvem avalia\u00e7\u00f5es e per\u00edcias.<\/p>\n<p>Durante a reuni\u00e3o, foi destacada a relev\u00e2ncia da integra\u00e7\u00e3o entre as \u00e1reas t\u00e9cnica e jur\u00eddica, refor\u00e7ando o papel das normas da ABNT como instrumentos fundamentais para garantir maior seguran\u00e7a, clareza e qualidade nos trabalhos periciais.<\/p>\n<p>A participa\u00e7\u00e3o da presidente do IBAPE e do conselheiro tamb\u00e9m integrou a agenda de divulga\u00e7\u00e3o da publica\u00e7\u00e3o <strong>\u201cA Norma de Per\u00edcias da ABNT para Operadores do Direito\u201d<\/strong>, que ser\u00e1 lan\u00e7ada em breve. A obra tem como objetivo contribuir para o entendimento e a aplica\u00e7\u00e3o das diretrizes t\u00e9cnicas por profissionais do direito, promovendo maior alinhamento entre engenharia, per\u00edcia e demandas jur\u00eddicas.<\/p>\n<\/div>\n<p><!--more--><\/p>\n<p><a href=\"https:\/\/ibape-nacional.com.br\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-18.08.18.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19061\" src=\"https:\/\/ibape-nacional.com.br\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-18.08.18.jpeg\" alt=\"\" width=\"700\" height=\"700\" srcset=\"https:\/\/ibape-nacional.com.br\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-18.08.18.jpeg 1600w, https:\/\/ibape-nacional.com.br\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-18.08.18-300x300.jpeg 300w, https:\/\/ibape-nacional.com.br\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-18.08.18-1024x1024.jpeg 1024w, https:\/\/ibape-nacional.com.br\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-18.08.18-150x150.jpeg 150w, https:\/\/ibape-nacional.com.br\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-18.08.18-768x768.jpeg 768w, https:\/\/ibape-nacional.com.br\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-18.08.18-1536x1536.jpeg 1536w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":293,"featured_media":19061,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[43],"tags":[],"class_list":["post-19060","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-e-destaques"],"acf":[],"_links":{"self":[{"href":"https:\/\/ibape-nacional.com.br\/site\/wp-json\/wp\/v2\/posts\/19060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibape-nacional.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ibape-nacional.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ibape-nacional.com.br\/site\/wp-json\/wp\/v2\/users\/293"}],"replies":[{"embeddable":true,"href":"https:\/\/ibape-nacional.com.br\/site\/wp-json\/wp\/v2\/comments?post=19060"}],"version-history":[{"count":2,"href":"https:\/\/ibape-nacional.com.br\/site\/wp-json\/wp\/v2\/posts\/19060\/revisions"}],"predecessor-version":[{"id":19063,"href":"https:\/\/ibape-nacional.com.br\/site\/wp-json\/wp\/v2\/posts\/19060\/revisions\/19063"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ibape-nacional.com.br\/site\/wp-json\/wp\/v2\/media\/19061"}],"wp:attachment":[{"href":"https:\/\/ibape-nacional.com.br\/site\/wp-json\/wp\/v2\/media?parent=19060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ibape-nacional.com.br\/site\/wp-json\/wp\/v2\/categories?post=19060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ibape-nacional.com.br\/site\/wp-json\/wp\/v2\/tags?post=19060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}